{"id":10006501,"date":"2022-04-15T16:10:13","date_gmt":"2022-04-15T22:10:13","guid":{"rendered":"https:\/\/scfd.org\/event\/dias-libres-de-scfd-en-four-mile-historic-park-2\/"},"modified":"2022-04-15T16:10:13","modified_gmt":"2022-04-15T22:10:13","slug":"dias-libres-de-scfd-en-four-mile-historic-park-2","status":"publish","type":"tribe_events","link":"https:\/\/scfd.org\/es\/event\/dias-libres-de-scfd-en-four-mile-historic-park-2\/2022-05-13\/","title":{"rendered":"D\u00edas libres de SCFD en Four Mile Historic Park"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":16,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"city":[36],"class_list":["post-10006501","tribe_events","type-tribe_events","status-publish","hentry","city-denver","tribe-recurring-event","tribe-recurring-event-parent"],"acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/tribe_events\/10006501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/users\/16"}],"version-history":[{"count":0,"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/tribe_events\/10006501\/revisions"}],"wp:attachment":[{"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/media?parent=10006501"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/tags?post=10006501"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=10006501"},{"taxonomy":"city","embeddable":true,"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/city?post=10006501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}