{"id":10008426,"date":"2024-01-04T12:25:28","date_gmt":"2024-01-04T19:25:28","guid":{"rendered":"https:\/\/scfd.org\/event\/viernes-gratis-en-four-mile-3\/"},"modified":"2024-01-04T12:25:28","modified_gmt":"2024-01-04T19:25:28","slug":"viernes-gratis-en-four-mile-3","status":"publish","type":"tribe_events","link":"https:\/\/scfd.org\/es\/event\/viernes-gratis-en-four-mile-3\/2024-06-28\/","title":{"rendered":"Viernes gratis en Four Mile"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":16,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"city":[36],"tribe_events_cat":[],"class_list":["post-10008426","tribe_events","type-tribe_events","status-publish","hentry","city-denver","tribe-recurring-event","tribe-recurring-event-parent"],"acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/tribe_events\/10008426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/users\/16"}],"version-history":[{"count":0,"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/tribe_events\/10008426\/revisions"}],"wp:attachment":[{"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/media?parent=10008426"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/tags?post=10008426"},{"taxonomy":"city","embeddable":true,"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/city?post=10008426"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=10008426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}