{"id":14685,"date":"2023-12-14T16:00:31","date_gmt":"2023-12-14T23:00:31","guid":{"rendered":"https:\/\/scfd.org\/event\/denver-childrens-theatre-presenta-tomas-y-la-senora-de-la-biblioteca\/"},"modified":"2023-12-14T16:00:31","modified_gmt":"2023-12-14T23:00:31","slug":"denver-childrens-theatre-presenta-tomas-y-la-senora-de-la-biblioteca","status":"publish","type":"tribe_events","link":"https:\/\/scfd.org\/es\/event\/denver-childrens-theatre-presenta-tomas-y-la-senora-de-la-biblioteca\/","title":{"rendered":"Denver Children&#8217;s Theatre presenta TOM\u00c1S Y LA SE\u00d1ORA DE LA BIBLIOTECA"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":16,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"city":[36],"class_list":["post-14685","tribe_events","type-tribe_events","status-publish","hentry","city-denver"],"acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/tribe_events\/14685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/users\/16"}],"version-history":[{"count":0,"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/tribe_events\/14685\/revisions"}],"wp:attachment":[{"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/media?parent=14685"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/tags?post=14685"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=14685"},{"taxonomy":"city","embeddable":true,"href":"https:\/\/scfd.org\/es\/wp-json\/wp\/v2\/city?post=14685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}